{"id":9485,"date":"2026-07-15T11:16:29","date_gmt":"2026-07-15T09:16:29","guid":{"rendered":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/?post_type=advert&#038;p=9485"},"modified":"2026-07-15T11:16:40","modified_gmt":"2026-07-15T09:16:40","slug":"grandeur-nature","status":"publish","type":"advert","link":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/advert\/grandeur-nature\/","title":{"rendered":"Grandeur Nature"},"content":{"rendered":"<p>Quel regard portons-nous sur notre environnement ? Que reste-il des espaces naturels ? Quels sentiments nous procure la rencontre avec les ph\u00e9nom\u00e8nes de la nature ?<\/p>\n<p>L\u2019exposition Grandeur Nature propose de formuler une r\u00e9ponse visuelle marquante \u00e0 ces questions en mettant en lumi\u00e8re les toiles et gravures de trois artistes qui interpr\u00e8tent les paysages naturels de mani\u00e8re radicalement diff\u00e9rente, instaurant ainsi un dialogue riche et puissant entre leurs oeuvres.<\/p>\n<p>Jeanne de Guillebon traduit avec une grande sensibilit\u00e9 le mouvement des paysages dans ses toiles et ses gravures.<\/p>\n<p>Martin Lassailly, architecte de formation, met subtilement en lumi\u00e8re dans ses peintures l\u2019opposition entre l\u2019ordre rectiligne des constructions humaines et le tumulte color\u00e9 et vivant de leur environnement direct.<\/p>\n<p>C\u00e9dric Selmi reformule les paysages naturels en aplats g\u00e9om\u00e9triques afin de faire ressortir l\u2019essentiel des perspectives, des couleurs et des sensations.<\/p>\n<p>Trois peintres, trois regards singuliers qui invitent le visiteur \u00e0 reconsid\u00e9rer la place qu\u2019il accorde \u00e0 sa relation avec l\u2019environnement et le poussent \u00e0 sortir de son quotidien pour aller ressentir et \u00e9prouver ce lien.<\/p>\n","protected":false},"author":0,"template":"","advert_category":[16],"class_list":["post-9485","classified","type-advert","status-publish","has-post-thumbnail","hentry","advert_category-art-contemporain"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert\/9485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert"}],"about":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/types\/advert"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/media\/9486"}],"wp:attachment":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/media?parent=9485"}],"wp:term":[{"taxonomy":"advert_category","embeddable":true,"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert_category?post=9485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}