{"id":2844,"date":"2022-11-05T10:39:06","date_gmt":"2022-11-05T09:39:06","guid":{"rendered":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/advert\/masculins-2\/"},"modified":"2022-12-05T10:40:28","modified_gmt":"2022-12-05T09:40:28","slug":"masculins-2","status":"expired","type":"advert","link":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/advert\/masculins-2\/","title":{"rendered":"Masculins"},"content":{"rendered":"<p>Exposition SOLO de Beno\u00eet L. d&rsquo;Hauterives du 18 au 27 novembre 2022. <em>Ouvert tous les jours de 11h \u00e0 19h en pr\u00e9sence de l&rsquo;artiste.<\/em><\/p>\n<p>Vernissage le Jeudi 17 novembre \u00e0 partir de 18h.<\/p>\n<p>N\u00e9 en 1967, Beno\u00eet L. d&rsquo;Hauterives vit et travaille entre Bordeaux et le Sud-Gironde.<\/p>\n<p>Ses peintures \u00e0 l\u2019huile, que les sujets soient \u00e9rudits ou plus banals, s\u2019impr\u00e8gnent toujours d\u2019une profonde empathie sur la nature humaine et d\u00e9voilent en filigrane la psychologie de son auteur, voire plus largement les tourments de son \u00e2me, cr\u00e9ant ainsi une atmosph\u00e8re charg\u00e9e d\u2019\u00e9motion et de sensibilit\u00e9.<\/p>\n<p>Profond\u00e9ment nourri des \u00ab\u00a0Classiques\u00a0\u00bb qu\u2019il n\u2019h\u00e9site pas \u00e0 revisiter, les faits de soci\u00e9t\u00e9 tels que les discriminations, les violences familiales, l\u2019homosexualit\u00e9 ou les questions de genre, sont autant de point de d\u00e9part qu\u2019il traite, se d\u00e9voilant souvent, sans jamais plonger dans un quelconque pros\u00e9lytisme. Les corps, le plus souvent masculins, trait\u00e9s \u00e0 l\u2019\u00e9conomie de traits et de mati\u00e8re faisant une large place \u00e0 la spontan\u00e9it\u00e9, semblent disparaitre derri\u00e8re une \u00e9paisse couche picturale trait\u00e9e au couteau, semblable aux \u00e9corces v\u00e9g\u00e9tales qu\u2019il photographie \u00e0 loisir, comme un t\u00e9moin de la dualit\u00e9 qui oppose aujourd\u2019hui la Nature et l\u2019Humanit\u00e9\u2026. A moins, qu\u2019au contraire, ils r\u00e9apparaissent, tels des fresques oubli\u00e9es derri\u00e8re les outrages du temps, pour r\u00e9v\u00e9ler l\u2019\u00e9vidence de la Beaut\u00e9 et de la Spiritualit\u00e9 dans le rapport complexe qu\u2019entretient l\u2019artiste et son sujet.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"author":244,"template":"","advert_category":[3,8],"class_list":["post-2844","classified","type-advert","status-expired","hentry","advert_category-peintures","advert_category-vernissages"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert\/2844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert"}],"about":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/types\/advert"}],"author":[{"embeddable":true,"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/users\/244"}],"wp:attachment":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/media?parent=2844"}],"wp:term":[{"taxonomy":"advert_category","embeddable":true,"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert_category?post=2844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}