{"id":2574,"date":"2022-09-20T22:14:00","date_gmt":"2022-09-20T20:14:00","guid":{"rendered":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/advert\/vernissage-pariseoul-double-double\/"},"modified":"2022-10-20T22:22:42","modified_gmt":"2022-10-20T20:22:42","slug":"vernissage-pariseoul-double-double","status":"expired","type":"advert","link":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/advert\/vernissage-pariseoul-double-double\/","title":{"rendered":"Vernissage &#8211; PARISEOUL DOUBLE DOUBLE"},"content":{"rendered":"<p class=\"_04xlpA direction-ltr align-center para-style-body\"><span class=\"JsGRdQ\">\u2604\ufe0f<strong>SAVE THE DATE<\/strong> \u2604\ufe0f<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-center para-style-body\"><span class=\"JsGRdQ\">Nous avons le plaisir de vous convier au vernissage <\/span><span class=\"JsGRdQ\">ce vendredi 23 septembre<\/span><span class=\"JsGRdQ\"> \u00e0 partir de 19h \u00e0 la Yellow Cube Gallery PARIS 13 pour d\u00e9couvrir l\u2019exposition :<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-center para-style-body\"><span class=\"JsGRdQ\">\u00a0\u00bb <strong>PARISEOUL \/ DEUX DEUX <\/strong><\/span><span class=\"JsGRdQ\">\u00ab\u00a0<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-center para-style-body\"><span class=\"JsGRdQ\">75070<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Dipl\u00f4m\u00e9s Beaux Art 2018, les Emmanuel Mousset et Moon se sont rencontr\u00e9s l\u00e0-bas et le collectif 75070 est ne\u00e9 : 75 pour Paris, 70 pour S\u00e9oul.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Ils s&rsquo;inspire de ce qu\u2019ils voient, de ce qu\u2019ils connaissent, la ville, mais surtout des figures hu- maines, habitants, enfants, toxicos, sportifs, histoires du quotidien&#8230;<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">La figuration est toujours pr\u00e9sente dans leur travail.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Apr\u00e8s une s\u00e9paration de 2 ans et demi, le collectif est de nouveau r\u00e9unis depuis cet \u00e9t\u00e9.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Woorim Moon a du rentrer en Cor\u00e9e en 2019 pour effectuer son service militaire obligatoire et d\u2019une dur\u00e9e de 2 ans c&rsquo;est donc une exposition marquante de ces retrouvailles.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">C\u2019est donc \u00e0 Paris, o\u00f9 vit et travaille Emmanuel Mousset que le duo s\u2019est retrouv\u00e9, avec le d\u00e9sir fort de faire rena\u00eetre dans l\u2019atelier, ce qui fait la particularit\u00e9 et la force de leur duo.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">C\u2019est \u00e0 dire, le fait de peindre \u00e0 quatres mains et \u00e0 deux t\u00eates, la vitesse de travail, le d\u00e9doublement, la passion du sport.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Le sport comme l\u2019un des beaux arts. Le sport qu\u2019ils dessinent et qu\u2019il peignent, qu\u2019ils examinent, athl\u00e9tiques jusque dans le geste, jusque dans le trait.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Les travaux collectifs auxquels il participe parfois sont dit-il comme autant de matchs, o\u00f9 en \u00e9quipe, on se fait des passes, on laisse jouer l\u2019autre, comme un combat. Et au centre, toujours, l\u2019humain. L\u2019humain comme une figure, qui revient, permanent sujet de ses \u0153uvres. L\u2019humain que l\u2019artiste aime regarder \u00e9voluer, sur le terrain, le ring ou dans la rue, qu\u2019il envisage comme une mati\u00e8re premi\u00e8re compos\u00e9e de hasards et d\u2019impr\u00e9vus.<\/span><\/p>\n<p><strong><span class=\"JsGRdQ\">Info pratique :<\/span><\/strong><\/p>\n<ul>\n<li class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Vernissage<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Vendredi 23 septembre 19H \/ 22H<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Exposition<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Vendredi 23 septembre au samedi 8 octobre 2022.<\/span><\/li>\n<\/ul>\n<p class=\"_04xlpA direction-ltr align-end para-style-body\"><strong><span class=\"JsGRdQ\">Yellow Cube Gallery <\/span><\/strong><span class=\"JsGRdQ\">:<\/span><\/p>\n<ul>\n<li class=\"_04xlpA direction-ltr align-end para-style-body\"><span class=\"JsGRdQ\">78 rue du Dessous Des Berges, 75013 PARIS<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-end para-style-body\"><span class=\"JsGRdQ\">Tram T3a, Station Avenue de France-M\u00e9tro ligne 14 ou RER C, Station Biblioth\u00e8que Fran\u00e7ois Mitterrand<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-end para-style-body\"><span class=\"JsGRdQ\">Ouvert du mardi au samedi de 12h \u00e0 19h<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-end para-style-body\"><span class=\"JsGRdQ\">Pour plus d\u2019information <\/span><span class=\"JsGRdQ\">:<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-end para-style-body\"><span class=\"JsGRdQ\">yellowcubegallery@gmail.com<\/span><\/li>\n<li class=\"_04xlpA direction-ltr align-end para-style-body\"><a class=\"JsGRdQ\" href=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fyellowcubegallery.com%2F%3Ffbclid%3DIwAR3xNdfK3lU_uwiySGbcV6KV4JpI_zv1Y066Qa48iJfkQoYW8kOKqg1x9IQ&amp;h=AT0v_GB1A_RknbKS65xT9EPQd8mKXV4uTVxLcml3LHcUNklnMy-Mvoy6TLl_5bgppENEMi0aI__TNK2FksvIcrKPH7z6YxWjk5S6PnZbdlqCPd6xTpFuSzM5lrFTDd-vTjgrSAG8bBbIOUUAfiqgP4oDpA&amp;__tn__=q&amp;c[0]=AT1Oipedcx5SKPSs0H-5_jyhVsCkbiQE_WaCWpieAZEuHFLc5WXCbinLgOdlpWcQuifijUG4B0XtSj6IqnhUg-VX5tKcWCJz-cqqzVDzQl0SwM8VD-Xq70nBeogl-dsYX_MOSpHrVAcy0iNLkV2GWMuAuhC6Wf2CtRpp_ifnzHCZec2fpQ\" target=\"_blank\" rel=\"noopener noreferrer\">yellowcubegallery.com<\/a><\/li>\n<li class=\"_04xlpA direction-ltr align-end para-style-body\"><span class=\"JsGRdQ\">Instagram : yellowcube.gallery<\/span><\/li>\n<\/ul>\n","protected":false},"author":33,"template":"","advert_category":[16],"class_list":["post-2574","classified","type-advert","status-expired","hentry","advert_category-art-contemporain"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert\/2574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert"}],"about":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/types\/advert"}],"author":[{"embeddable":true,"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/users\/33"}],"wp:attachment":[{"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/media?parent=2574"}],"wp:term":[{"taxonomy":"advert_category","embeddable":true,"href":"https:\/\/www.exposition-paris.info\/galeries-art-paris\/wp-json\/wp\/v2\/advert_category?post=2574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}